{"id":16863,"date":"2025-03-18T17:06:22","date_gmt":"2025-03-18T21:06:22","guid":{"rendered":"https:\/\/solutionswill.com\/?page_id=16863"},"modified":"2025-05-07T16:47:50","modified_gmt":"2025-05-07T20:47:50","slug":"canadian-carbon-credits","status":"publish","type":"page","link":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/","title":{"rendered":"Canadian carbon credits: offsetting emissions locally"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;Hero&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;e68aa8c9-06e1-48cb-b82b-29ec720aed4c&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#ffffff 50%|rgba(255,255,255,0) 50%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0.5)&#8221; background_color_gradient_end=&#8221;rgba(0,0,0,0.75)&#8221; background_image=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/patrick-hendry-cZrKRPZz0A-unsplash-scaled.jpg&#8221; background_position=&#8221;top_center&#8221; custom_padding=&#8221;0vw||0vw||true|false&#8221; custom_padding_tablet=&#8221;10vw||10vw||true|false&#8221; custom_padding_phone=&#8221;10vw||10vw||true|false&#8221; background_last_edited=&#8221;on|tablet&#8221; use_background_color_gradient_tablet=&#8221;on&#8221; background_color_gradient_direction_tablet=&#8221;180deg&#8221; background_color_gradient_stops_tablet=&#8221;#ffffff 70%|rgba(255,255,255,0) 70%&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Empower Your Business with Canadian Carbon Credits&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;f0c675ea-2574-4d0e-b725-30f8550a8550&#8243; title_level=&#8221;h4&#8243; title_font=&#8221;IBM Plex Sans|IBM Plex Sans Condensed_weight||on|||||&#8221; title_text_color=&#8221;#F04E2A&#8221; title_font_size=&#8221;14px&#8221; title_letter_spacing=&#8221;1px&#8221; title_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_text_align_tablet=&#8221;center&#8221; title_text_align_phone=&#8221;center&#8221; title_text_align_last_edited=&#8221;on|phone&#8221; title_font_size_tablet=&#8221;13px&#8221; title_font_size_phone=&#8221;13px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#22577a%22:%91%22title_text_color%22,%22title_text_color%22,%22title_text_color%22%93}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;Support Canada&#8217;s Economy, Embrace Sustainability&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;ddeb8c09-9078-4424-bc15-2efb6572e28e&#8221; title_font=&#8221;|IBM Plex Sans Condensed_weight|||||||&#8221; title_text_color=&#8221;#2A524C&#8221; title_font_size=&#8221;46px&#8221; title_line_height=&#8221;1.15em&#8221; custom_margin=&#8221;||16px|||&#8221; title_text_align_tablet=&#8221;center&#8221; title_text_align_phone=&#8221;center&#8221; title_text_align_last_edited=&#8221;on|phone&#8221; title_font_size_tablet=&#8221;40px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text quote_border_color=&#8221;#57cc99&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; text_text_color=&#8221;#19302D&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; link_text_color=&#8221;#22577a&#8221; quote_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; text_orientation_tablet=&#8221;center&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Join the movement to strengthen Canadian economic sovereignty while contributing to a sustainable future. Purchase Canadian carbon credits from local projects and make a tangible impact today.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#form-Canada&#8221; button_text=&#8221;Get a quote&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#F04E2A&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;|600|||||||&#8221; button_icon=&#8221;&#xf276;||fa||900&#8243; custom_padding=&#8221;||||true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/solutionswill.com\/en\/produit\/sustainable-community-carbon-credit\/&#8221; button_text=&#8221;Buy online&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#F04E2A&#8221; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_width=&#8221;2px&#8221; button_border_color=&#8221;#F04E2A&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;|600|||||||&#8221; button_icon=&#8221;&#xf07a;||fa||900&#8243; button_icon_color=&#8221;#F04E2A&#8221; custom_padding=&#8221;||||true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221; button_icon_color__hover_enabled=&#8221;on|desktop&#8221; button_icon_color__hover=&#8221;#F04E2A&#8221; button_border_color__hover_enabled=&#8221;on|hover&#8221; button_border_color__hover=&#8221;#F04E2A&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; custom_padding=&#8221;8%||8%||false|false&#8221; custom_padding_tablet=&#8221;0%||8%||false|false&#8221; custom_padding_phone=&#8221;0%||8%||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(170,187,169,0.25)&#8221; custom_padding=&#8221;50px||31px||false|false&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; custom_padding=&#8221;3px||5px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Navigating Economic Challenges with Local Solutions&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;ba4a6336-701f-47b8-bf5c-09da0ce28016&#8243; title_level=&#8221;h3&#8243; title_font=&#8221;|IBM Plex Sans Condensed_weight|||||||&#8221; title_text_color=&#8221;#2A524C&#8221; title_font_size=&#8221;35px&#8221; title_line_height=&#8221;1.1em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_text_align_tablet=&#8221;center&#8221; title_text_align_phone=&#8221;center&#8221; title_text_align_last_edited=&#8221;on|tablet&#8221; title_font_size_tablet=&#8221;22px&#8221; title_font_size_phone=&#8221;17px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text quote_border_color=&#8221;#57cc99&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; text_text_color=&#8221;#19302D&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; link_text_color=&#8221;#22577a&#8221; quote_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; text_orientation_tablet=&#8221;center&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>In the face of rising US tariffs and growing economic protectionism, Canadian companies are at a crossroads. The economic tensions between Canada and the United States highlight the urgent need to bolster our local economy. By prioritizing Canadian initiatives, businesses can not only safeguard their interests but also contribute to national economic resilience.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; text_orientation_tablet=&#8221;center&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Supporting local projects is more than a patriotic choice; it&#8217;s a strategic move to ensure energy independence and sustainable growth. As the buy-local movement gains momentum, Canadian companies have a unique opportunity to lead by example, reinforcing their commitment to decarbonization and corporate social responsibility.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/Visuel-Local.png&#8221; title_text=&#8221;Visuel &#8211; Local&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; width_tablet=&#8221;30%&#8221; width_phone=&#8221;50%&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover=&#8221;105%|105%&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,2_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;3px||3px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/Visuel-Parcours.png&#8221; title_text=&#8221;Visuel &#8211; Parcours&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; width_tablet=&#8221;30%&#8221; width_phone=&#8221;50%&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover=&#8221;105%|105%&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; text_orientation_tablet=&#8221;center&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>By investing in Canadian carbon credits, businesses can play a pivotal role in the ecological transition, creating sustainable jobs and enhancing local expertise. This approach not only aligns with corporate values but also positions companies as leaders in the fight against climate change.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px||49px||false|&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;5px||3px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Our credits support Canadian GHG reduction projects, all under one banner!&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;ba4a6336-701f-47b8-bf5c-09da0ce28016&#8243; title_level=&#8221;h3&#8243; title_font=&#8221;|IBM Plex Sans Condensed_weight|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#2A524C&#8221; title_font_size=&#8221;35px&#8221; title_line_height=&#8221;1.1em&#8221; custom_margin=&#8221;||28px||false|false&#8221; title_font_size_tablet=&#8221;22px&#8221; title_font_size_phone=&#8221;17px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_gallery gallery_ids=&#8221;16964,16962,16960,16956&#8243; gallery_orderby=&#8221;rand&#8221; posts_number=&#8221;3&#8243; show_pagination=&#8221;off&#8221; disabled_on=&#8221;on|off|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h4&#8243; title_font=&#8221;|600|on||||||&#8221; title_font_size=&#8221;14px&#8221; caption_font=&#8221;||||||||&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; animation_style=&#8221;fade&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;2000ms&#8221; border_radii_image=&#8221;on|20px|20px|20px|20px&#8221; box_shadow_style_image=&#8221;preset2&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover=&#8221;105%|105%&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_gallery][et_pb_gallery gallery_ids=&#8221;16958,16966,16968,16970&#8243; gallery_orderby=&#8221;rand&#8221; posts_number=&#8221;3&#8243; show_pagination=&#8221;off&#8221; disabled_on=&#8221;on|off|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h4&#8243; title_font=&#8221;|600|on||||||&#8221; title_font_size=&#8221;14px&#8221; caption_font=&#8221;||||||||&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; animation_style=&#8221;fade&#8221; animation_direction=&#8221;right&#8221; animation_duration=&#8221;2000ms&#8221; border_radii_image=&#8221;on|20px|20px|20px|20px&#8221; box_shadow_style_image=&#8221;preset2&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover=&#8221;105%|105%&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_gallery][et_pb_gallery gallery_ids=&#8221;16964,16962,16960,16956&#8243; gallery_orderby=&#8221;rand&#8221; disabled_on=&#8221;off|on|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h4&#8243; title_font=&#8221;|600|on||||||&#8221; title_font_size=&#8221;14px&#8221; caption_font=&#8221;||||||||&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;70%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; animation_style=&#8221;fade&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;2000ms&#8221; border_radii_image=&#8221;on|20px|20px|20px|20px&#8221; box_shadow_style_image=&#8221;preset2&#8243; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover=&#8221;105%|105%&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_gallery][et_pb_gallery gallery_ids=&#8221;16958,16966,16968,16970&#8243; gallery_orderby=&#8221;rand&#8221; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h4&#8243; title_font=&#8221;|600|on||||||&#8221; title_font_size=&#8221;14px&#8221; caption_font=&#8221;||||||||&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;70%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; animation_style=&#8221;fade&#8221; animation_direction=&#8221;right&#8221; animation_duration=&#8221;2000ms&#8221; border_radii_image=&#8221;on|20px|20px|20px|20px&#8221; box_shadow_style_image=&#8221;preset2&#8243; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover=&#8221;105%|105%&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|auto|1px|auto||&#8221; custom_padding=&#8221;34px||2px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;#form-Canada&#8221; button_text=&#8221;contact a sales consultant&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#F04E2A&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;|600|||||||&#8221; button_icon=&#8221;&#xf51e;||fa||900&#8243; custom_padding=&#8221;||||true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/solutionswill.com\/en\/produit\/sustainable-community-carbon-credit\/&#8221; button_text=&#8221;Buy Online&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#F04E2A&#8221; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_width=&#8221;2px&#8221; button_border_color=&#8221;#F04E2A&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;|600|||||||&#8221; button_icon=&#8221;&#xf07a;||fa||900&#8243; button_icon_color=&#8221;#F04E2A&#8221; custom_padding=&#8221;||||true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221; button_icon_color__hover_enabled=&#8221;on|desktop&#8221; button_icon_color__hover=&#8221;#F04E2A&#8221; button_border_color__hover_enabled=&#8221;on|hover&#8221; button_border_color__hover=&#8221;#F04E2A&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/Montreal-scaled.jpg&#8221; custom_padding=&#8221;100px||100px||true|&#8221; custom_padding_tablet=&#8221;100px||100px||true|&#8221; custom_padding_phone=&#8221;30px||30px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;3px||2px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;28px&#8221; text_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; text_font_size_tablet=&#8221;28px&#8221; text_font_size_phone=&#8221;28px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_text_shadow_style=&#8221;preset4&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-size: xx-large;\"><strong>Millions of dollars<\/strong> <strong>leave Canada every year<\/strong> because of U.S. and foreign carbon credits purchases. Let&#8217;s buy Canadian carbon credits and support our local economy.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_mask_style=&#8221;on&#8221; background_mask_style=&#8221;floating-squares&#8221; background_mask_color=&#8221;rgba(42,94,91,0.24)&#8221; background_mask_transform=&#8221;invert&#8221; custom_padding=&#8221;47px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|700|||||||&#8221; text_font_size=&#8221;26px&#8221; text_line_height=&#8221;1.2em&#8221; header_font_size=&#8221;33px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||25px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"color: #29524a;\">Get a quote, request a demo, present your decarbonization objectives or simply obtain a quote for the purchase of your Canadian carbon credits!<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2021\/04\/PierreGravelPFP_circle-cropped-2.png&#8221; alt=&#8221;Pierre Gravel, Carbon Credit Sales Manager, for the Sustainable Community&#8217;s portfolio of Canadian carbon credits&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;15%&#8221; width_tablet=&#8221;20%&#8221; width_phone=&#8221;50%&#8221; width_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;fold&#8221; animation_duration=&#8221;1500ms&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221; transform_scale__hover=&#8221;108%|108%&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #29524a;\">Pierre Gravel\u00a0<\/span><\/strong><br \/><span style=\"color: #29524a;\"><strong>Carbon Credits Sales Manager<\/strong><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;form-Canada&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;|auto|1px|auto||&#8221; custom_padding=&#8221;||26px|||&#8221; animation_style=&#8221;zoom&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;1500ms&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#AABBA9&#8243; box_shadow_style=&#8221;preset2&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover=&#8221;103%|103%&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_contact_form use_spam_service=&#8221;on&#8221; recaptcha_list=&#8221;Default|Default-0&#8243; email=&#8221;sales@solutionswill.com, pgravel@solutionswill.com, marketing@solutionswill.com&#8221; title=&#8221;Contact Pierre to get started&#8221; custom_message=&#8221;Prospect has completed the Canadian credits form (Local carbon credits landing page).||et_pb_line_break_holder||||et_pb_line_break_holder||First Name: %%First_Name%%||et_pb_line_break_holder||Last Name: %%Last_Name%%||et_pb_line_break_holder||Email: %%Email%%||et_pb_line_break_holder||Phone: %%Phone%%||et_pb_line_break_holder||Company Name: %%Entreprise%%||et_pb_line_break_holder||||et_pb_line_break_holder||Message: %%Message%%&#8221; use_redirect=&#8221;on&#8221; redirect_url=&#8221;https:\/\/solutionswill.com\/en\/thank-you-for-contacting-us\/&#8221; success_message=&#8221;Message sent!&#8221; submit_button_text=&#8221;Send Now&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;f5b8e026-f002-46cf-b6c2-91e536e7a590&#8243; form_field_background_color=&#8221;RGBA(0,0,0,0)&#8221; form_field_text_color=&#8221;#AABBA9&#8243; form_field_focus_text_color=&#8221;#2A524C&#8221; form_field_custom_margin=&#8221;5px||5px||true|false&#8221; form_field_custom_padding=&#8221;8px||8px||true|false&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Montserrat|700|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#F04E2A&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;1.4em&#8221; captcha_font=&#8221;|600|||||||&#8221; captcha_line_height=&#8221;1.9em&#8221; form_field_font=&#8221;|600|||||||&#8221; form_field_text_align=&#8221;center&#8221; form_field_font_size=&#8221;15px&#8221; form_field_line_height=&#8221;1.6em&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#F04E2A&#8221; button_border_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_radius=&#8221;30px&#8221; button_font=&#8221;|600|||||||&#8221; button_icon=&#8221;&#xf1d8;||fa||900&#8243; button_custom_margin=&#8221;50px||||false|false&#8221; text_orientation=&#8221;center&#8221; width=&#8221;100%&#8221; width_tablet=&#8221;90%&#8221; width_phone=&#8221;85%&#8221; width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-2px|30px|-2px|30px|true|true&#8221; custom_padding=&#8221;0px|20px|20px|20px|false|true&#8221; form_field_font_size_tablet=&#8221;14px&#8221; form_field_font_size_phone=&#8221;14px&#8221; form_field_font_size_last_edited=&#8221;on|phone&#8221; button_text_size_tablet=&#8221;18px&#8221; button_text_size_phone=&#8221;16px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; module_alignment_tablet=&#8221;center&#8221; module_alignment_phone=&#8221;center&#8221; module_alignment_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#AABBA9&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#FFFFFF&#8221; transform_styles__hover_enabled=&#8221;on|desktop&#8221; transform_scale__hover_enabled=&#8221;on|desktop&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#F04E2A&#8221; form_field_text_color__hover_enabled=&#8221;on|desktop&#8221; form_field_text_color__hover=&#8221;#AABBA9&#8243; button_bg_enable_color__hover=&#8221;on&#8221;][et_pb_contact_field field_id=&#8221;First_Name&#8221; field_title=&#8221;First Name&#8221; max_length=&#8221;30&#8243; _builder_version=&#8221;4.27.4&#8243; form_field_text_color=&#8221;#AABBA9&#8243; form_field_font=&#8221;||||||||&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#777777&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Last_Name&#8221; field_title=&#8221;Last Name&#8221; max_length=&#8221;30&#8243; _builder_version=&#8221;4.19.4&#8243; form_field_text_color=&#8221;#AABBA9&#8243; form_field_font=&#8221;||||||||&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#777777&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;Email&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.25.1&#8243; form_field_text_color=&#8221;#AABBA9&#8243; form_field_font=&#8221;||||||||&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#777777&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Phone&#8221; field_title=&#8221;Phone&#8221; allowed_symbols=&#8221;numbers&#8221; _builder_version=&#8221;4.27.4&#8243; form_field_text_color=&#8221;#AABBA9&#8243; form_field_font=&#8221;||||||||&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#777777&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Entreprise&#8221; field_title=&#8221;Company name&#8221; _builder_version=&#8221;4.27.4&#8243; form_field_text_color=&#8221;#AABBA9&#8243; form_field_font=&#8221;||||||||&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#777777&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Message&#8221; field_title=&#8221;Your message&#8221; field_type=&#8221;text&#8221; required_mark=&#8221;off&#8221; _builder_version=&#8221;4.27.2&#8243; form_field_text_color=&#8221;#AABBA9&#8243; form_field_font=&#8221;||||||||&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#777777&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Features&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;48px||30px|||&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; custom_margin=&#8221;|auto|-10px|auto|false|false&#8221; custom_padding=&#8221;6px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Why Choose Canadian Carbon Credits?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#2A524C&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; custom_padding_tablet=&#8221;||0px||false|false&#8221; custom_padding_phone=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Unmatched Quality Assurance&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf14a;||fa||400&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;32px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22%93}&#8221;]<\/p>\n<p>Our carbon credits are sourced from rigorously verified projects, ensuring the highest standards of environmental integrity and effectiveness.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Comprehensive Traceability&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf689;||fa||900&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;32px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;]<\/p>\n<p>Each credit is fully traceable, providing transparency and accountability throughout the entire lifecycle of the carbon offset process.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; custom_padding_tablet=&#8221;||0px||false|false&#8221; custom_padding_phone=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Local Economic Impact&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf785;||fa||400&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;32px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;]<\/p>\n<p>Investing in our credits means directly supporting Canadian communities, fostering economic growth and sustainable development.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Commitment to Sustainability&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf06c;||fa||900&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;28px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;]<\/p>\n<p>Our projects are designed to drive meaningful change, contributing to Canada&#8217;s ecological goals and promoting long-term environmental stewardship.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|auto|1px|auto||&#8221; custom_padding=&#8221;||2px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/solutionswill.com\/en\/produit\/sustainable-community-carbon-credit\/&#8221; button_text=&#8221;Buy online&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#F04E2A&#8221; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_width=&#8221;2px&#8221; button_border_color=&#8221;#F04E2A&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;|600|||||||&#8221; button_icon=&#8221;&#xf07a;||fa||900&#8243; button_icon_color=&#8221;#F04E2A&#8221; custom_padding=&#8221;||||true|true&#8221; button_text_size_tablet=&#8221;18px&#8221; button_text_size_phone=&#8221;16px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221; button_icon_color__hover_enabled=&#8221;on|desktop&#8221; button_icon_color__hover=&#8221;#F04E2A&#8221; button_border_color__hover_enabled=&#8221;on|hover&#8221; button_border_color__hover=&#8221;#F04E2A&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/www.newswire.ca\/news-releases\/carbon-credits-millions-of-dollars-spent-in-the-united-states-every-year-will-solutions-takes-action&#8211;857098566.html&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;View our related press release&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#2A524C&#8221; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_width=&#8221;2px&#8221; button_border_color=&#8221;#2A524C&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;|600|||||||&#8221; button_icon=&#8221;&#xf09e;||fa||900&#8243; custom_padding=&#8221;||||true|true&#8221; button_text_size_tablet=&#8221;18px&#8221; button_text_size_phone=&#8221;16px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221; button_border_color__hover_enabled=&#8221;on|desktop&#8221; button_border_color__hover=&#8221;#2A524C&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;#AABBA9&#8243; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||12px|||&#8221; custom_padding=&#8221;36px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;10px||0px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Businesses across Canada trust our local carbon credits.&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#2A524C&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width_tablet=&#8221;90%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/Bandeau-logo-Canada-FR-1.png&#8221; alt=&#8221;Logo Banner &#8211; Customers and Partners Will Solutions&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;29px||29px|||&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; custom_padding=&#8221;3px||6px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;#AABBA9&#8243; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||12px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_heading title=&#8221;Economic Benefits for Canadian Companies&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#2A524C&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; custom_padding=&#8221;||3px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;30px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;-20px&#8221; box_shadow_color=&#8221;RGBA(255,255,255,0)&#8221; box_shadow_color_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.2)&#8221;][et_pb_blurb title=&#8221;Energy Independence&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf0e7;||fa||900&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;32px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22,%22icon_color%22%93}&#8221;]<\/p>\n<p>By purchasing our Canadian carbon credits, companies support local eco-industrial initiatives, reducing reliance on foreign energy sources.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;30px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;-20px&#8221; box_shadow_color=&#8221;RGBA(255,255,255,0)&#8221; box_shadow_color_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.2)&#8221;][et_pb_blurb title=&#8221;Sustainable Job Creation&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe0f4;||divi||400&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;32px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;]<\/p>\n<p>Investing in our local carbon credits fosters job growth in green sectors, enhancing Canadian expertise and contributing to the ecological transition.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;30px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;-20px&#8221; box_shadow_color=&#8221;RGBA(255,255,255,0)&#8221; box_shadow_color_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.2)&#8221;][et_pb_blurb title=&#8221;Local Economic Impact&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf276;||fa||900&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;32px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;]<\/p>\n<p>Each purchase reinvests capital into the Canadian economy, strengthening local businesses and communities.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; custom_padding=&#8221;||3px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;30px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;-20px&#8221; box_shadow_color=&#8221;RGBA(255,255,255,0)&#8221; box_shadow_color_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.2)&#8221;][et_pb_blurb title=&#8221;Environmental Responsibility&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf06c;||fa||900&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;32px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;]<\/p>\n<p>Supporting our Canadian carbon projects demonstrates a tangible commitment to sustainability and ESG.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;30px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;-20px&#8221; box_shadow_color=&#8221;RGBA(255,255,255,0)&#8221; box_shadow_color_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.2)&#8221;][et_pb_blurb title=&#8221;Add Value to Local Businesses&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf3b2;||fa||400&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;32px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;]<\/p>\n<p>Our carbon credits come from a group of Canadian local SMEs, NPOs and collectivities, developping concrete decarbonation projects on their production chains.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;30px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;-20px&#8221; box_shadow_color=&#8221;RGBA(255,255,255,0)&#8221; box_shadow_color_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.2)&#8221;][et_pb_blurb title=&#8221;Reach new markets&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf012;||fa||900&#8243; icon_color=&#8221;#F04E2A&#8221; image_icon_width=&#8221;32px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F04E2A&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#22577a&#8221; body_link_font_size=&#8221;14px&#8221; background_mask_style=&#8221;diagonal-bars&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#3c3a47%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22#57cc99%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;]<\/p>\n<p>meet the growing demand for locally committed companies, increase customers loyalty and employees retention rate.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Testimonials&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|||||&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; custom_padding=&#8221;3px||6px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;#AABBA9&#8243; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||12px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_icon font_icon=&#8221;&#xf10d;||fa||900&#8243; icon_color=&#8221;#F04E2A&#8221; icon_width=&#8221;32px&#8221; module_class=&#8221;ai_ignore_font_icon&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;c2c23269-d09e-4bca-9247-65cd5ecf15a9&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#57cc99%22:%91%22icon_color%22%93}&#8221;][\/et_pb_icon][et_pb_heading title=&#8221;What Our Clients Say&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#2A524C&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2024\/07\/Josee-Vaillancourt-Directrice-Communication-et-Fondation-St-Hubert.jpg&#8221; title_text=&#8221;new-portrait-12-800&#215;800&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;6ed8fd5c-62c5-4100-98c3-7b8b6d2c2ee6&#8243; max_height=&#8221;100px&#8221; border_radii=&#8221;on|300px|300px|300px|300px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text quote_border_color=&#8221;#57cc99&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;ca5459fa-2abd-4000-9b59-3cb483bcc17e&#8221; text_font=&#8221;||on||||||&#8221; text_text_color=&#8221;#19302D&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_text_color=&#8221;#22577a&#8221; quote_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||10px||false|false&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#22577a%22:%91%22link_text_color%22,%22link_text_color%22,%22link_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_4_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22,%22header_5_text_color%22,%22header_6_text_color%22,%22quote_text_color%22,%22text_text_color%22%93,%22#57cc99%22:%91%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22%93}&#8221;]<\/p>\n<p>\u201cThanks to Will Solutions and their support, we have transformed our fleet of delivery vehicles into a carbon-neutral business. It is thanks to the purchase of carbon credits that St Hubert is once again able to position itself as a leader in the restaurant industry [\u2026].\u201c<\/p>\n<p>[\/et_pb_text][et_pb_text quote_border_color=&#8221;#57cc99&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; text_text_color=&#8221;#19302D&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; link_text_color=&#8221;#22577a&#8221; quote_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Jos\u00e9e Vaillancourt, Director of Communications<br \/><strong>St-Hubert<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; custom_padding_tablet=&#8221;30px||||false|false&#8221; custom_padding_phone=&#8221;30px||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2024\/07\/Denyse-Remillard-Universite-de-Sherbrooke-scaled.jpg&#8221; title_text=&#8221;new-portrait-7-800&#215;800&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;6ed8fd5c-62c5-4100-98c3-7b8b6d2c2ee6&#8243; max_height=&#8221;100px&#8221; border_radii=&#8221;on|300px|300px|300px|300px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text quote_border_color=&#8221;#57cc99&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;ca5459fa-2abd-4000-9b59-3cb483bcc17e&#8221; text_font=&#8221;||on||||||&#8221; text_text_color=&#8221;#19302D&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_text_color=&#8221;#22577a&#8221; quote_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||10px||false|false&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#22577a%22:%91%22link_text_color%22,%22link_text_color%22,%22link_text_color%22,%22link_text_color%22,%22link_text_color%22,%22link_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_4_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22,%22header_5_text_color%22,%22header_6_text_color%22,%22quote_text_color%22,%22text_text_color%22,%22header_text_color%22,%22header_4_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22,%22header_5_text_color%22,%22header_6_text_color%22,%22quote_text_color%22,%22text_text_color%22%93,%22#57cc99%22:%91%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22%93}&#8221;]<\/p>\n<p>\u201cThe University of Sherbrooke is proud to encourage Quebec projects such as Sustainable Community of Quebec offered by Will Solutions in achieving its carbon neutrality.\u201c\u00a0<\/p>\n<p>[\/et_pb_text][et_pb_text quote_border_color=&#8221;#57cc99&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; text_text_color=&#8221;#19302D&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; link_text_color=&#8221;#22577a&#8221; quote_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Denyse R\u00e9millard, Vice-Rector, Administration and Sustainable Development<br \/><strong>University of Sherbrooke.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; custom_padding_tablet=&#8221;30px||||false|false&#8221; custom_padding_phone=&#8221;30px||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2024\/06\/Ski-Saint-Bruno-Vicki_profil_linkedin-scaled.webp&#8221; title_text=&#8221;new-portrait-8-800&#215;800&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;6ed8fd5c-62c5-4100-98c3-7b8b6d2c2ee6&#8243; max_height=&#8221;100px&#8221; border_radii=&#8221;on|300px|300px|300px|300px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text quote_border_color=&#8221;#57cc99&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;ca5459fa-2abd-4000-9b59-3cb483bcc17e&#8221; text_font=&#8221;||on||||||&#8221; text_text_color=&#8221;#19302D&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_text_color=&#8221;#22577a&#8221; quote_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;IBM Plex Sans Condensed|700|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||10px||false|false&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#22577a%22:%91%22link_text_color%22,%22link_text_color%22,%22link_text_color%22,%22link_text_color%22,%22link_text_color%22,%22link_text_color%22,%22link_text_color%22,%22link_text_color%22,%22link_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_4_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22,%22header_5_text_color%22,%22header_6_text_color%22,%22quote_text_color%22,%22text_text_color%22,%22header_text_color%22,%22header_4_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22,%22header_5_text_color%22,%22header_6_text_color%22,%22quote_text_color%22,%22text_text_color%22,%22header_text_color%22,%22header_4_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22,%22header_5_text_color%22,%22header_6_text_color%22,%22quote_text_color%22,%22text_text_color%22%93,%22#57cc99%22:%91%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22,%22quote_border_color%22%93}&#8221;]<\/p>\n<p>\u201cThanks to Will Solutions\u2019 expertise, we identified the main sources of emissions and implemented concrete actions to reduce our carbon footprint\u201d\u00a0<\/p>\n<p>[\/et_pb_text][et_pb_text quote_border_color=&#8221;#57cc99&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; text_text_color=&#8221;#19302D&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_font=&#8221;|IBM Plex Sans_weight|||||||&#8221; link_text_color=&#8221;#22577a&#8221; quote_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;IBM Plex Sans Condensed|IBM Plex Sans Condensed_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Vicki M\u00e9nard, Senior Marketing Coordinator and Sustainability Project Manager<br \/><strong>Ski Saint Bruno<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Call to Action&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(196,196,196,0.5) 0%|rgba(10,10,10,0.5) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/Image-profil-Sweep-WILL-Copie-scaled-1-scaled.jpg&#8221; custom_padding=&#8221;5vw||5vw||true|false&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22background_color%22%93}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_cta title=&#8221;Take Action with Canadian Carbon Credits&#8221; button_url=&#8221;#form-Canada&#8221; button_text=&#8221;Contact Us Today&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;4c2ad5d0-871e-414e-a4be-aa9134d4ae8e&#8221; header_font=&#8221;&#8211;et_global_heading_font|IBM Plex Sans Condensed_weight|||||||&#8221; header_text_color=&#8221;#2A524C&#8221; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.2em&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; background_color=&#8221;rgba(255,255,255,0.83)&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#F04E2A&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;|600|||||||&#8221; button_icon=&#8221;&#xf0e0;||fa||900&#8243; button_custom_padding=&#8221;||||true|true&#8221; background_layout=&#8221;light&#8221; custom_padding=&#8221;29px|60px|29px|60px|true|true&#8221; custom_padding_tablet=&#8221;30px|30px|30px|30px|true|true&#8221; custom_padding_phone=&#8221;20px|20px|20px|20px|true|true&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;28px&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;16px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; button_text_size_tablet=&#8221;18px&#8221; button_text_size_phone=&#8221;16px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-f2943306-fa6c-45f0-b632-5fc00151366a%22:%91%22button_text_color%22%93,%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22button_text_color%22,%22color%22,%22background_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22color%22,%22color%22,%22color%22,%22color%22%93,%22gcid-f113ad93-2527-46d7-862b-fc71181c6b5e%22:%91%22border_color_all%22,%22border_color_all%22%93}&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221;]<\/p>\n<p>Support the local economy while meeting your carbon neutrality objectives. Join the movement towards a sustainable future by investing in Canadian carbon credits. Contact Will Solutions to discover how your company can benefit from supporting local projects and contributing to a greener economy.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Join the movement to strengthen Canadian economic sovereignty while contributing to a sustainable future. Purchase Canadian carbon credits from local projects and make a tangible impact today.In the face of rising US tariffs and growing economic protectionism, Canadian companies are at a crossroads. The economic tensions between Canada and the United States highlight the urgent [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":16872,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-16863","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Canadian carbon credits: offsetting emissions locally<\/title>\n<meta name=\"description\" content=\"Support the local economy and offset your emissions with Canadian carbon credits from Solutions Will. Verified projects with high environmental impact.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canadian carbon credits: offsetting emissions locally\" \/>\n<meta property=\"og:description\" content=\"Support the local economy and offset your emissions with Canadian carbon credits from Solutions Will. Verified projects with high environmental impact.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/\" \/>\n<meta property=\"og:site_name\" content=\"Solution Will\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SolutionsWill\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T20:47:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/patrick-hendry-cZrKRPZz0A-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WILL_Solutions\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/canadian-carbon-credits\\\/\",\"url\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/canadian-carbon-credits\\\/\",\"name\":\"Canadian carbon credits: offsetting emissions locally\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/canadian-carbon-credits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/canadian-carbon-credits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solutionswill.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/patrick-hendry-cZrKRPZz0A-unsplash-scaled.jpg\",\"datePublished\":\"2025-03-18T21:06:22+00:00\",\"dateModified\":\"2025-05-07T20:47:50+00:00\",\"description\":\"Support the local economy and offset your emissions with Canadian carbon credits from Solutions Will. Verified projects with high environmental impact.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/canadian-carbon-credits\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solutionswill.com\\\/en\\\/canadian-carbon-credits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/canadian-carbon-credits\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solutionswill.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/patrick-hendry-cZrKRPZz0A-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/solutionswill.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/patrick-hendry-cZrKRPZz0A-unsplash-scaled.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"Canadian carbon credits - Buy Local is voting - Will Solutions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/canadian-carbon-credits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canadian carbon credits: offsetting emissions locally\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/\",\"name\":\"Solution Will\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/#organization\",\"name\":\"Solutions Will\",\"url\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/secureservercdn.net\\\/198.71.233.33\\\/ljr.809.myftpupload.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logoWillSolutions.jpg?time=1654012899\",\"contentUrl\":\"https:\\\/\\\/secureservercdn.net\\\/198.71.233.33\\\/ljr.809.myftpupload.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logoWillSolutions.jpg?time=1654012899\",\"width\":900,\"height\":409,\"caption\":\"Solutions Will\"},\"image\":{\"@id\":\"https:\\\/\\\/solutionswill.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SolutionsWill\\\/\",\"https:\\\/\\\/x.com\\\/WILL_Solutions\",\"https:\\\/\\\/www.instagram.com\\\/creditscarbone\\\/\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/will-solutions\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canadian carbon credits: offsetting emissions locally","description":"Support the local economy and offset your emissions with Canadian carbon credits from Solutions Will. Verified projects with high environmental impact.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/","og_locale":"en_US","og_type":"article","og_title":"Canadian carbon credits: offsetting emissions locally","og_description":"Support the local economy and offset your emissions with Canadian carbon credits from Solutions Will. Verified projects with high environmental impact.","og_url":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/","og_site_name":"Solution Will","article_publisher":"https:\/\/www.facebook.com\/SolutionsWill\/","article_modified_time":"2025-05-07T20:47:50+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/patrick-hendry-cZrKRPZz0A-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@WILL_Solutions","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/","url":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/","name":"Canadian carbon credits: offsetting emissions locally","isPartOf":{"@id":"https:\/\/solutionswill.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/#primaryimage"},"image":{"@id":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/#primaryimage"},"thumbnailUrl":"https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/patrick-hendry-cZrKRPZz0A-unsplash-scaled.jpg","datePublished":"2025-03-18T21:06:22+00:00","dateModified":"2025-05-07T20:47:50+00:00","description":"Support the local economy and offset your emissions with Canadian carbon credits from Solutions Will. Verified projects with high environmental impact.","breadcrumb":{"@id":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/#primaryimage","url":"https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/patrick-hendry-cZrKRPZz0A-unsplash-scaled.jpg","contentUrl":"https:\/\/solutionswill.com\/wp-content\/uploads\/2025\/03\/patrick-hendry-cZrKRPZz0A-unsplash-scaled.jpg","width":2048,"height":1365,"caption":"Canadian carbon credits - Buy Local is voting - Will Solutions"},{"@type":"BreadcrumbList","@id":"https:\/\/solutionswill.com\/en\/canadian-carbon-credits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solutionswill.com\/en\/accueil\/"},{"@type":"ListItem","position":2,"name":"Canadian carbon credits: offsetting emissions locally"}]},{"@type":"WebSite","@id":"https:\/\/solutionswill.com\/en\/#website","url":"https:\/\/solutionswill.com\/en\/","name":"Solution Will","description":"","publisher":{"@id":"https:\/\/solutionswill.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solutionswill.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/solutionswill.com\/en\/#organization","name":"Solutions Will","url":"https:\/\/solutionswill.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/solutionswill.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/secureservercdn.net\/198.71.233.33\/ljr.809.myftpupload.com\/wp-content\/uploads\/2022\/05\/logoWillSolutions.jpg?time=1654012899","contentUrl":"https:\/\/secureservercdn.net\/198.71.233.33\/ljr.809.myftpupload.com\/wp-content\/uploads\/2022\/05\/logoWillSolutions.jpg?time=1654012899","width":900,"height":409,"caption":"Solutions Will"},"image":{"@id":"https:\/\/solutionswill.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SolutionsWill\/","https:\/\/x.com\/WILL_Solutions","https:\/\/www.instagram.com\/creditscarbone\/","http:\/\/www.linkedin.com\/company\/will-solutions"]}]}},"_links":{"self":[{"href":"https:\/\/solutionswill.com\/en\/wp-json\/wp\/v2\/pages\/16863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solutionswill.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solutionswill.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solutionswill.com\/en\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/solutionswill.com\/en\/wp-json\/wp\/v2\/comments?post=16863"}],"version-history":[{"count":25,"href":"https:\/\/solutionswill.com\/en\/wp-json\/wp\/v2\/pages\/16863\/revisions"}],"predecessor-version":[{"id":17647,"href":"https:\/\/solutionswill.com\/en\/wp-json\/wp\/v2\/pages\/16863\/revisions\/17647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solutionswill.com\/en\/wp-json\/wp\/v2\/media\/16872"}],"wp:attachment":[{"href":"https:\/\/solutionswill.com\/en\/wp-json\/wp\/v2\/media?parent=16863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}